{"id":1058,"date":"2025-04-22T17:40:55","date_gmt":"2025-04-22T17:40:55","guid":{"rendered":"https:\/\/enjooybarcelona.com\/?post_type=product&#038;p=1058"},"modified":"2025-12-19T16:41:25","modified_gmt":"2025-12-19T16:41:25","slug":"barcelona-vs-celta-de-vigo","status":"publish","type":"product","link":"https:\/\/enjooybarcelona.com\/es\/producto\/barcelona-vs-celta-de-vigo\/","title":{"rendered":"Barcelona VS Celta de Vigo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":901,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[39],"product_tag":[],"class_list":{"0":"post-1058","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-laliga","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v26.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barcelona VS Celta de Vigo - Enjooy Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enjooybarcelona.com\/es\/producto\/barcelona-vs-celta-de-vigo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona VS Celta de Vigo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enjooybarcelona.com\/es\/producto\/barcelona-vs-celta-de-vigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Enjooy Barcelona\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T16:41:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1370\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilidad\" \/>\n\t<meta name=\"twitter:data1\" content=\"Disponible\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/\",\"url\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/\",\"name\":\"Barcelona VS Celta de Vigo - Enjooy Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/enjooybarcelona.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp\",\"datePublished\":\"2025-04-22T17:40:55+00:00\",\"dateModified\":\"2025-12-19T16:41:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#primaryimage\",\"url\":\"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp\",\"contentUrl\":\"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp\",\"width\":1370,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/enjooybarcelona.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\/\/enjooybarcelona.com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barcelona VS Celta de Vigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/enjooybarcelona.com\/#website\",\"url\":\"https:\/\/enjooybarcelona.com\/\",\"name\":\"Enjooy Barcelona\",\"description\":\"Tickets\",\"publisher\":{\"@id\":\"https:\/\/enjooybarcelona.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/enjooybarcelona.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/enjooybarcelona.com\/#organization\",\"name\":\"Enjooy Barcelona\",\"url\":\"https:\/\/enjooybarcelona.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/enjooybarcelona.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2024\/12\/enjooy-barcelona.webp\",\"contentUrl\":\"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2024\/12\/enjooy-barcelona.webp\",\"width\":752,\"height\":299,\"caption\":\"Enjooy Barcelona\"},\"image\":{\"@id\":\"https:\/\/enjooybarcelona.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Barcelona VS Celta de Vigo - Enjooy Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enjooybarcelona.com\/es\/producto\/barcelona-vs-celta-de-vigo\/","og_locale":"es_ES","og_type":"article","og_title":"Barcelona VS Celta de Vigo","og_url":"https:\/\/enjooybarcelona.com\/es\/producto\/barcelona-vs-celta-de-vigo\/","og_site_name":"Enjooy Barcelona","article_modified_time":"2025-12-19T16:41:25+00:00","og_image":[{"width":1370,"height":1600,"url":"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilidad":"Disponible"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/","url":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/","name":"Barcelona VS Celta de Vigo - Enjooy Barcelona","isPartOf":{"@id":"https:\/\/enjooybarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#primaryimage"},"image":{"@id":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#primaryimage"},"thumbnailUrl":"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp","datePublished":"2025-04-22T17:40:55+00:00","dateModified":"2025-12-19T16:41:25+00:00","breadcrumb":{"@id":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#primaryimage","url":"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp","contentUrl":"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2025\/12\/barcelona-0.webp","width":1370,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/enjooybarcelona.com\/product\/barcelona-vs-celta-de-vigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enjooybarcelona.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/enjooybarcelona.com\/"},{"@type":"ListItem","position":3,"name":"Barcelona VS Celta de Vigo"}]},{"@type":"WebSite","@id":"https:\/\/enjooybarcelona.com\/#website","url":"https:\/\/enjooybarcelona.com\/","name":"Enjooy Barcelona","description":"Tickets","publisher":{"@id":"https:\/\/enjooybarcelona.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enjooybarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/enjooybarcelona.com\/#organization","name":"Enjooy Barcelona","url":"https:\/\/enjooybarcelona.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/enjooybarcelona.com\/#\/schema\/logo\/image\/","url":"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2024\/12\/enjooy-barcelona.webp","contentUrl":"https:\/\/enjooybarcelona.com\/wp-content\/uploads\/2024\/12\/enjooy-barcelona.webp","width":752,"height":299,"caption":"Enjooy Barcelona"},"image":{"@id":"https:\/\/enjooybarcelona.com\/#\/schema\/logo\/image\/"}}]},"og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/product\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/comments?post=1058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/media\/901"}],"wp:attachment":[{"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/product_brand?post=1058"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/product_cat?post=1058"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/enjooybarcelona.com\/es\/wp-json\/wp\/v2\/product_tag?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}